{"id":9,"date":"2019-07-29T06:20:43","date_gmt":"2019-07-29T06:20:43","guid":{"rendered":"https:\/\/demosites.io\/rokophoto\/?page_id=9"},"modified":"2021-12-04T08:28:30","modified_gmt":"2021-12-04T08:28:30","slug":"bae34-rokophoto-home","status":"publish","type":"page","link":"https:\/\/vetreality.erasmus.site\/it\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9\" class=\"elementor elementor-9\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f872ca elementor-section-height-min-height animated-slow elementor-section-boxed elementor-section-height-default elementor-section-items-middle elementor-invisible\" data-id=\"9f872ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d2a44e\" data-id=\"2d2a44e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8e486b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8e486b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c537180\" data-id=\"c537180\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b190bf3 elementor-widget elementor-widget-heading\" data-id=\"b190bf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">VET Reality<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-126c14c elementor-widget elementor-widget-text-editor\" data-id=\"126c14c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Virtual Reality based training to<br \/>upskill VET Teachers and Trainers<br \/>and foster inclusion of SEN Students in WBL<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e0ce5f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4e0ce5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/vetreality.erasmus.site\/#about\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Il progetto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38b78ae elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"38b78ae\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-95cf8d1\" data-id=\"95cf8d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-66ff759 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66ff759\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4993e97\" data-id=\"4993e97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b671513 elementor-widget elementor-widget-menu-anchor\" data-id=\"b671513\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"about\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48ce992 elementor-widget elementor-widget-heading\" data-id=\"48ce992\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il progetto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bbe8be elementor-widget elementor-widget-spacer\" data-id=\"2bbe8be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b59bcda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b59bcda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ee6356e\" data-id=\"ee6356e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43621c3 elementor-widget elementor-widget-text-editor\" data-id=\"43621c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><p><\/p><p>La realt\u00e0 virtuale \u00e8 difficilmente rappresentata a livello dell&#8217;IFP nel quadro delle esperienze di apprendimento basate sul lavoro (WBL) in particolare per gli studenti BES. VETREALITY cerca di contribuire all&#8217;istruzione e alla digitalizzazione dell&#8217;UE e mira a sensibilizzare gli insegnanti e i formatori dell&#8217;IFP su come gestire e integrare la tecnologia VR nei propri programmi di insegnamento per facilitare l&#8217;accesso degli studenti con bisogni speciali al WBL. Il progetto \u00e8 complementare alla partnership e sviluppa strumenti innovativi a livello dell&#8217;UE che sono in linea con le seguenti priorit\u00e0 sottolineate nell&#8217;Agenda UE 2020 e nell&#8217;Agenda 2030 per uno sviluppo sostenibile delle Nazioni Unite: insegnamento inclusivo, competenze digitali, wbl e mobilit\u00e0 per studenti BES.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c92dd1d elementor-button-danger elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c92dd1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vetreality.erasmus.site\/about\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Continua a leggere<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c74b33b\" data-id=\"c74b33b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-068f981 elementor-widget elementor-widget-image\" data-id=\"068f981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"626\" height=\"626\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/Image-1@1X.png\" class=\"elementor-animation-hang attachment-large size-large wp-image-111\" alt=\"\" srcset=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/Image-1@1X.png 626w, https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/Image-1@1X-300x300.png 300w, https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/Image-1@1X-150x150.png 150w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3a0700 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a3a0700\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0ea6c7\" data-id=\"c0ea6c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d47a956 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d47a956\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9850911\" data-id=\"9850911\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c320618 elementor-widget elementor-widget-heading\" data-id=\"c320618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">Opere dell'ingegno<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b59e1a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b59e1a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-116cf1a\" data-id=\"116cf1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a16bf38 elementor-widget elementor-widget-image\" data-id=\"a16bf38\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"221\" height=\"221\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/books@1X.png\" class=\"elementor-animation-buzz-out attachment-large size-large wp-image-121\" alt=\"\" srcset=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/books@1X.png 221w, https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/books@1X-150x150.png 150w\" sizes=\"(max-width: 221px) 100vw, 221px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f12e994 elementor-alert-danger elementor-widget elementor-widget-alert\" data-id=\"f12e994\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Output #1<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">e-Compendio<\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1861c6a elementor-button-danger elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1861c6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vetreality.erasmus.site\/o1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Continua a leggere<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0feb705\" data-id=\"0feb705\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03f0a0c elementor-widget elementor-widget-image\" data-id=\"03f0a0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"232\" height=\"237\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/note@1X.png\" class=\"elementor-animation-buzz-out attachment-large size-large wp-image-122\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b58e2b elementor-alert-danger elementor-widget elementor-widget-alert\" data-id=\"9b58e2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Output #2<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">Programma di formazione<\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce5f64a elementor-button-danger elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ce5f64a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vetreality.erasmus.site\/o2\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Continua a leggere<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f857392\" data-id=\"f857392\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a194b44 elementor-widget elementor-widget-image\" data-id=\"a194b44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"258\" height=\"226\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/laptop@1X.png\" class=\"elementor-animation-buzz-out attachment-large size-large wp-image-124\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-037134f elementor-alert-danger elementor-widget elementor-widget-alert\" data-id=\"037134f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Output #3<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">Tool Box per la Mobilit\u00e0<\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06f8495 elementor-button-danger elementor-align-center elementor-widget elementor-widget-button\" data-id=\"06f8495\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vetreality.erasmus.site\/o3\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Continua a leggere<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d101b7f elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"d101b7f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89bfd53\" data-id=\"89bfd53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b04794c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b04794c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4e5190f\" data-id=\"4e5190f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bf4a65 elementor-widget elementor-widget-heading\" data-id=\"3bf4a65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Partner<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c6240c elementor-widget elementor-widget-spacer\" data-id=\"6c6240c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-28ef811 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28ef811\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-044cba6\" data-id=\"044cba6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e08149a elementor-widget elementor-widget-image\" data-id=\"e08149a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/coso-300x300.png\" class=\"elementor-animation-grow attachment-medium size-medium wp-image-242\" alt=\"\" srcset=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/coso.png 300w, https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/coso-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a8cbed6\" data-id=\"a8cbed6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fdccca elementor-widget elementor-widget-image\" data-id=\"2fdccca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/reattiva-300x300.png\" class=\"elementor-animation-grow attachment-medium size-medium wp-image-243\" alt=\"\" srcset=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/reattiva.png 300w, https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/reattiva-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-36c5ed8\" data-id=\"36c5ed8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e730c02 elementor-widget elementor-widget-image\" data-id=\"e730c02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/auxilum-300x300.png\" class=\"elementor-animation-grow attachment-medium size-medium wp-image-239\" alt=\"\" srcset=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/auxilum.png 300w, https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/auxilum-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c9fcb83\" data-id=\"c9fcb83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-725fae0 elementor-widget elementor-widget-image\" data-id=\"725fae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/danmar-300x300.png\" class=\"elementor-animation-grow attachment-medium size-medium wp-image-238\" alt=\"\" srcset=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/danmar.png 300w, https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/danmar-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f64a623 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f64a623\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8fbb7a9\" data-id=\"8fbb7a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7adfb37 elementor-widget elementor-widget-image\" data-id=\"7adfb37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/inshea-300x300.png\" class=\"elementor-animation-grow attachment-medium size-medium wp-image-241\" alt=\"\" srcset=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/inshea.png 300w, https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/inshea-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9c58098\" data-id=\"9c58098\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8743fb8 elementor-widget elementor-widget-image\" data-id=\"8743fb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/inmakulada-300x300.png\" class=\"elementor-animation-grow attachment-medium size-medium wp-image-244\" alt=\"\" srcset=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/inmakulada.png 300w, https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/inmakulada-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7cc2eb6\" data-id=\"7cc2eb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3f2a0d elementor-widget elementor-widget-image\" data-id=\"f3f2a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/ectb-300x300.png\" class=\"elementor-animation-grow attachment-medium size-medium wp-image-240\" alt=\"\" srcset=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/ectb.png 300w, https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/ectb-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>VET Reality Virtual Reality based training toupskill VET Teachers and Trainersand foster inclusion of SEN Students in WBL Il progetto Il progetto La realt\u00e0 virtuale \u00e8 difficilmente rappresentata a livello dell&#8217;IFP nel quadro delle esperienze di apprendimento basate sul lavoro (WBL) in particolare per gli studenti BES. VETREALITY cerca di contribuire all&#8217;istruzione e alla digitalizzazione&hellip;&nbsp;<a href=\"https:\/\/vetreality.erasmus.site\/it\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Home<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - VETReality<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vetreality.erasmus.site\/it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - VETReality\" \/>\n<meta property=\"og:description\" content=\"VET Reality Virtual Reality based training toupskill VET Teachers and Trainersand foster inclusion of SEN Students in WBL Il progetto Il progetto La realt\u00e0 virtuale \u00e8 difficilmente rappresentata a livello dell&#8217;IFP nel quadro delle esperienze di apprendimento basate sul lavoro (WBL) in particolare per gli studenti BES. VETREALITY cerca di contribuire all&#8217;istruzione e alla digitalizzazione&hellip;&nbsp;Leggi tutto &raquo;Home\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vetreality.erasmus.site\/it\/\" \/>\n<meta property=\"og:site_name\" content=\"VETReality\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VETRealityEU\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-04T08:28:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/Image-1@1X.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/\",\"url\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/\",\"name\":\"Home - VETReality\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vetreality.erasmus.site\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Image-1@1X.png\",\"datePublished\":\"2019-07-29T06:20:43+00:00\",\"dateModified\":\"2021-12-04T08:28:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vetreality.erasmus.site\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Image-1@1X.png\",\"contentUrl\":\"https:\\\/\\\/vetreality.erasmus.site\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Image-1@1X.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/\",\"name\":\"VETReality\",\"description\":\"Project\",\"publisher\":{\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/#organization\",\"name\":\"VETreality Project\",\"url\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vetreality.erasmus.site\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-cropped-Logo-Vetreality.jpg\",\"contentUrl\":\"https:\\\/\\\/vetreality.erasmus.site\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-cropped-Logo-Vetreality.jpg\",\"width\":512,\"height\":512,\"caption\":\"VETreality Project\"},\"image\":{\"@id\":\"https:\\\/\\\/vetreality.erasmus.site\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VETRealityEU\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - VETReality","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vetreality.erasmus.site\/it\/","og_locale":"it_IT","og_type":"article","og_title":"Home - VETReality","og_description":"VET Reality Virtual Reality based training toupskill VET Teachers and Trainersand foster inclusion of SEN Students in WBL Il progetto Il progetto La realt\u00e0 virtuale \u00e8 difficilmente rappresentata a livello dell&#8217;IFP nel quadro delle esperienze di apprendimento basate sul lavoro (WBL) in particolare per gli studenti BES. VETREALITY cerca di contribuire all&#8217;istruzione e alla digitalizzazione&hellip;&nbsp;Leggi tutto &raquo;Home","og_url":"https:\/\/vetreality.erasmus.site\/it\/","og_site_name":"VETReality","article_publisher":"https:\/\/www.facebook.com\/VETRealityEU","article_modified_time":"2021-12-04T08:28:30+00:00","og_image":[{"url":"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/Image-1@1X.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vetreality.erasmus.site\/it\/","url":"https:\/\/vetreality.erasmus.site\/it\/","name":"Home - VETReality","isPartOf":{"@id":"https:\/\/vetreality.erasmus.site\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vetreality.erasmus.site\/it\/#primaryimage"},"image":{"@id":"https:\/\/vetreality.erasmus.site\/#primaryimage"},"thumbnailUrl":"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/Image-1@1X.png","datePublished":"2019-07-29T06:20:43+00:00","dateModified":"2021-12-04T08:28:30+00:00","breadcrumb":{"@id":"https:\/\/vetreality.erasmus.site\/it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/vetreality.erasmus.site\/it\/"]]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vetreality.erasmus.site\/it\/#primaryimage","url":"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/Image-1@1X.png","contentUrl":"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/Image-1@1X.png"},{"@type":"BreadcrumbList","@id":"https:\/\/vetreality.erasmus.site\/it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vetreality.erasmus.site\/it\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/vetreality.erasmus.site\/it\/#website","url":"https:\/\/vetreality.erasmus.site\/it\/","name":"VETReality","description":"Project","publisher":{"@id":"https:\/\/vetreality.erasmus.site\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vetreality.erasmus.site\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/vetreality.erasmus.site\/it\/#organization","name":"VETreality Project","url":"https:\/\/vetreality.erasmus.site\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vetreality.erasmus.site\/it\/#\/schema\/logo\/image\/","url":"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/cropped-cropped-Logo-Vetreality.jpg","contentUrl":"https:\/\/vetreality.erasmus.site\/wp-content\/uploads\/2021\/03\/cropped-cropped-Logo-Vetreality.jpg","width":512,"height":512,"caption":"VETreality Project"},"image":{"@id":"https:\/\/vetreality.erasmus.site\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VETRealityEU"]}]}},"_links":{"self":[{"href":"https:\/\/vetreality.erasmus.site\/it\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vetreality.erasmus.site\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vetreality.erasmus.site\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vetreality.erasmus.site\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vetreality.erasmus.site\/it\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":132,"href":"https:\/\/vetreality.erasmus.site\/it\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":549,"href":"https:\/\/vetreality.erasmus.site\/it\/wp-json\/wp\/v2\/pages\/9\/revisions\/549"}],"wp:attachment":[{"href":"https:\/\/vetreality.erasmus.site\/it\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}